{"id":24909,"date":"2017-03-14T17:16:07","date_gmt":"2017-03-14T16:16:07","guid":{"rendered":"http:\/\/sdg21.eu\/?post_type=blog&#038;p=24909"},"modified":"2020-11-26T17:17:54","modified_gmt":"2020-11-26T16:17:54","slug":"bbsr-broschueren-ueber-oekobaudat-und-wecobis","status":"publish","type":"blog","link":"https:\/\/sdg21.eu\/en\/blog\/bbsr-broschueren-ueber-oekobaudat-und-wecobis","title":{"rendered":"BBSR brochures on \u00d6KOBAUDAT and WECOBIS"},"content":{"rendered":"<p>The Federal Institute for Research on Building, Urban Affairs and Spatial Development (BBSR) has published two brochures providing information on the \u00d6KOBAUDAT and WECOBIS portals.<\/p>\n<p>WECOBIS - Web-based ecological building material information system<br \/>\nDownload (PDF, 5MB)<br \/>\n<a href=\"https:\/\/www.bbsr.bund.de\/BBSR\/DE\/veroeffentlichungen\/zukunft-bauen-fp\/2014-16\/band-07.html\" target=\"_blank\" rel=\"noopener noreferrer\">www.bbsr.bund.de\/...2014-16\/band-07-dl.pdf<\/a><\/p>\n<p>\u00d6KOBAUDAT - basis for life cycle assessment<br \/>\nDownload (PDF, 7MB)<br \/>\n<a href=\"https:\/\/www.bbsr.bund.de\/BBSR\/DE\/veroeffentlichungen\/zukunft-bauen-fp\/2017\/band-09.html\" target=\"_blank\" rel=\"noopener noreferrer\">www.bbsr.bund.de\/...2017\/band-09-dl.pdf<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>The Federal Institute for Research on Building, Urban Affairs and Spatial Development (BBSR) has published two brochures providing information on the portals \u00d6KOBAUDAT and WECOBIS. WECOBIS - Web-based ecological building materials information system Download (PDF, 5MB) www.bbsr.bund.de\/...2014-16\/band-07-dl.pdf \u00d6KOBAUDAT - Basis for life cycle assessment Download (PDF, 7MB) www.bbsr.bund.de\/...2017\/band-09-dl.pdf<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"template":"","format":"standard","blog-kategorie":[830,758,924,775,840,778,912,891,828],"blog-schlagwort":[],"class_list":{"0":"post-24909","1":"blog","2":"type-blog","3":"status-publish","4":"format-standard","6":"blog-kategorie-baustoffe-konstruktion","7":"blog-kategorie-bundesland","8":"blog-kategorie-forschung","9":"blog-kategorie-holzbau","10":"blog-kategorie-nawarohs","11":"blog-kategorie-neue-buecher-und-studien","12":"blog-kategorie-oekobilanz","13":"blog-kategorie-tools","14":"blog-kategorie-zertifzierung-labels","15":"gallery-content-unit","16":"czr-hentry"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Das Bundesinstitut f\u00fcr Bau-, Stadt- und Raumforschung (BBSR) hat zwei Brosch\u00fcren ver\u00f6ffentlicht, die \u00fcber die Portale \u00d6KOBAUDAT und WECOBIS informieren. WECOBIS \u2013 Webbasiertes \u00f6kologisches Baustoffinformationssystem Download (PDF, 5MB) www.bbsr.bund.de\/...2014-16\/band-07-dl.pdf \u00d6KOBAUDAT - Grundlage f\u00fcr die \u00d6kobilanzierung Download (PDF, 7MB) www.bbsr.bund.de\/...2017\/band-09-dl.pdf\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"sdg21-Redaktion\"\/>\n\t<meta name=\"google-site-verification\" content=\"google-site-verification=iM5-SDV9qoipUL1b4I0aVhHIOQi1wv0MougIaW1ugnQ\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/sdg21.eu\/en\/blog\/bbsr-broschueren-ueber-oekobaudat-und-wecobis\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog\\\/bbsr-broschueren-ueber-oekobaudat-und-wecobis#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog#listItem\",\"name\":\"Blog-Beitr\\u00e4ge\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog#listItem\",\"position\":2,\"name\":\"Blog-Beitr\\u00e4ge\",\"item\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog-kategorie\\\/oekologie#listItem\",\"name\":\"\\u00d6kologie\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog-kategorie\\\/oekologie#listItem\",\"position\":3,\"name\":\"\\u00d6kologie\",\"item\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog-kategorie\\\/oekologie\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog-kategorie\\\/oekologie\\\/baustoffe-konstruktion#listItem\",\"name\":\"Baustoffe \\\/ Konstruktion\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog#listItem\",\"name\":\"Blog-Beitr\\u00e4ge\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog-kategorie\\\/oekologie\\\/baustoffe-konstruktion#listItem\",\"position\":4,\"name\":\"Baustoffe \\\/ Konstruktion\",\"item\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog-kategorie\\\/oekologie\\\/baustoffe-konstruktion\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog-kategorie\\\/oekologie\\\/baustoffe-konstruktion\\\/holzbau#listItem\",\"name\":\"Holzbau\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog-kategorie\\\/oekologie#listItem\",\"name\":\"\\u00d6kologie\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog-kategorie\\\/oekologie\\\/baustoffe-konstruktion\\\/holzbau#listItem\",\"position\":5,\"name\":\"Holzbau\",\"item\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog-kategorie\\\/oekologie\\\/baustoffe-konstruktion\\\/holzbau\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog\\\/bbsr-broschueren-ueber-oekobaudat-und-wecobis#listItem\",\"name\":\"BBSR-Brosch\\u00fcren \\u00fcber \\u00d6KOBAUDAT und WECOBIS\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog-kategorie\\\/oekologie\\\/baustoffe-konstruktion#listItem\",\"name\":\"Baustoffe \\\/ Konstruktion\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog\\\/bbsr-broschueren-ueber-oekobaudat-und-wecobis#listItem\",\"position\":6,\"name\":\"BBSR-Brosch\\u00fcren \\u00fcber \\u00d6KOBAUDAT und WECOBIS\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog-kategorie\\\/oekologie\\\/baustoffe-konstruktion\\\/holzbau#listItem\",\"name\":\"Holzbau\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/#person\",\"name\":\"sdg21-Redaktion\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/author\\\/wolpensinger#author\",\"url\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/author\\\/wolpensinger\",\"name\":\"sdg21-Redaktion\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog\\\/bbsr-broschueren-ueber-oekobaudat-und-wecobis#webpage\",\"url\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog\\\/bbsr-broschueren-ueber-oekobaudat-und-wecobis\",\"name\":\"BBSR-Brosch\\u00fcren \\u00fcber \\u00d6KOBAUDAT und WECOBIS | sdg21\",\"description\":\"Das Bundesinstitut f\\u00fcr Bau-, Stadt- und Raumforschung (BBSR) hat zwei Brosch\\u00fcren ver\\u00f6ffentlicht, die \\u00fcber die Portale \\u00d6KOBAUDAT und WECOBIS informieren. WECOBIS \\u2013 Webbasiertes \\u00f6kologisches Baustoffinformationssystem Download (PDF, 5MB) www.bbsr.bund.de\\\/...2014-16\\\/band-07-dl.pdf \\u00d6KOBAUDAT - Grundlage f\\u00fcr die \\u00d6kobilanzierung Download (PDF, 7MB) www.bbsr.bund.de\\\/...2017\\\/band-09-dl.pdf\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog\\\/bbsr-broschueren-ueber-oekobaudat-und-wecobis#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/author\\\/wolpensinger#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/author\\\/wolpensinger#author\"},\"datePublished\":\"2017-03-14T17:16:07+01:00\",\"dateModified\":\"2020-11-26T17:17:54+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/\",\"name\":\"sdg21\",\"description\":\"Webdatenbank nachhaltiger Siedlungen und Quartiere\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"BBSR brochures on \u00d6KOBAUDAT and WECOBIS | sdg21","description":"The Federal Institute for Research on Building, Urban Affairs and Spatial Development (BBSR) has published two brochures providing information on the \u00d6KOBAUDAT and WECOBIS portals. WECOBIS - Web-based ecological building material information system Download (PDF, 5MB) www.bbsr.bund.de\/...2014-16\/band-07-dl.pdf \u00d6KOBAUDAT - Basis for life cycle assessment Download (PDF, 7MB) www.bbsr.bund.de\/...2017\/band-09-dl.pdf","canonical_url":"https:\/\/sdg21.eu\/en\/blog\/bbsr-broschueren-ueber-oekobaudat-und-wecobis","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"google-site-verification=iM5-SDV9qoipUL1b4I0aVhHIOQi1wv0MougIaW1ugnQ","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/sdg21.eu\/en\/blog\/bbsr-broschueren-ueber-oekobaudat-und-wecobis#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/sdg21.eu\/en\/#listItem","position":1,"name":"Home","item":"https:\/\/sdg21.eu\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/sdg21.eu\/en\/blog#listItem","name":"Blog-Beitr\u00e4ge"}},{"@type":"ListItem","@id":"https:\/\/sdg21.eu\/en\/blog#listItem","position":2,"name":"Blog-Beitr\u00e4ge","item":"https:\/\/sdg21.eu\/en\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/sdg21.eu\/en\/blog-kategorie\/oekologie#listItem","name":"\u00d6kologie"},"previousItem":{"@type":"ListItem","@id":"https:\/\/sdg21.eu\/en\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/sdg21.eu\/en\/blog-kategorie\/oekologie#listItem","position":3,"name":"\u00d6kologie","item":"https:\/\/sdg21.eu\/en\/blog-kategorie\/oekologie","nextItem":{"@type":"ListItem","@id":"https:\/\/sdg21.eu\/en\/blog-kategorie\/oekologie\/baustoffe-konstruktion#listItem","name":"Baustoffe \/ Konstruktion"},"previousItem":{"@type":"ListItem","@id":"https:\/\/sdg21.eu\/en\/blog#listItem","name":"Blog-Beitr\u00e4ge"}},{"@type":"ListItem","@id":"https:\/\/sdg21.eu\/en\/blog-kategorie\/oekologie\/baustoffe-konstruktion#listItem","position":4,"name":"Baustoffe \/ Konstruktion","item":"https:\/\/sdg21.eu\/en\/blog-kategorie\/oekologie\/baustoffe-konstruktion","nextItem":{"@type":"ListItem","@id":"https:\/\/sdg21.eu\/en\/blog-kategorie\/oekologie\/baustoffe-konstruktion\/holzbau#listItem","name":"Holzbau"},"previousItem":{"@type":"ListItem","@id":"https:\/\/sdg21.eu\/en\/blog-kategorie\/oekologie#listItem","name":"\u00d6kologie"}},{"@type":"ListItem","@id":"https:\/\/sdg21.eu\/en\/blog-kategorie\/oekologie\/baustoffe-konstruktion\/holzbau#listItem","position":5,"name":"Holzbau","item":"https:\/\/sdg21.eu\/en\/blog-kategorie\/oekologie\/baustoffe-konstruktion\/holzbau","nextItem":{"@type":"ListItem","@id":"https:\/\/sdg21.eu\/en\/blog\/bbsr-broschueren-ueber-oekobaudat-und-wecobis#listItem","name":"BBSR-Brosch\u00fcren \u00fcber \u00d6KOBAUDAT und WECOBIS"},"previousItem":{"@type":"ListItem","@id":"https:\/\/sdg21.eu\/en\/blog-kategorie\/oekologie\/baustoffe-konstruktion#listItem","name":"Baustoffe \/ Konstruktion"}},{"@type":"ListItem","@id":"https:\/\/sdg21.eu\/en\/blog\/bbsr-broschueren-ueber-oekobaudat-und-wecobis#listItem","position":6,"name":"BBSR-Brosch\u00fcren \u00fcber \u00d6KOBAUDAT und WECOBIS","previousItem":{"@type":"ListItem","@id":"https:\/\/sdg21.eu\/en\/blog-kategorie\/oekologie\/baustoffe-konstruktion\/holzbau#listItem","name":"Holzbau"}}]},{"@type":"Person","@id":"https:\/\/sdg21.eu\/en\/#person","name":"sdg21-Redaktion"},{"@type":"Person","@id":"https:\/\/sdg21.eu\/en\/author\/wolpensinger#author","url":"https:\/\/sdg21.eu\/en\/author\/wolpensinger","name":"sdg21-Redaktion"},{"@type":"WebPage","@id":"https:\/\/sdg21.eu\/en\/blog\/bbsr-broschueren-ueber-oekobaudat-und-wecobis#webpage","url":"https:\/\/sdg21.eu\/en\/blog\/bbsr-broschueren-ueber-oekobaudat-und-wecobis","name":"BBSR-Brosch\u00fcren \u00fcber \u00d6KOBAUDAT und WECOBIS | sdg21","description":"Das Bundesinstitut f\u00fcr Bau-, Stadt- und Raumforschung (BBSR) hat zwei Brosch\u00fcren ver\u00f6ffentlicht, die \u00fcber die Portale \u00d6KOBAUDAT und WECOBIS informieren. WECOBIS \u2013 Webbasiertes \u00f6kologisches Baustoffinformationssystem Download (PDF, 5MB) www.bbsr.bund.de\/...2014-16\/band-07-dl.pdf \u00d6KOBAUDAT - Grundlage f\u00fcr die \u00d6kobilanzierung Download (PDF, 7MB) www.bbsr.bund.de\/...2017\/band-09-dl.pdf","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/sdg21.eu\/en\/#website"},"breadcrumb":{"@id":"https:\/\/sdg21.eu\/en\/blog\/bbsr-broschueren-ueber-oekobaudat-und-wecobis#breadcrumblist"},"author":{"@id":"https:\/\/sdg21.eu\/en\/author\/wolpensinger#author"},"creator":{"@id":"https:\/\/sdg21.eu\/en\/author\/wolpensinger#author"},"datePublished":"2017-03-14T17:16:07+01:00","dateModified":"2020-11-26T17:17:54+01:00"},{"@type":"WebSite","@id":"https:\/\/sdg21.eu\/en\/#website","url":"https:\/\/sdg21.eu\/en\/","name":"sdg21","description":"Webdatenbank nachhaltiger Siedlungen und Quartiere","inLanguage":"en-GB","publisher":{"@id":"https:\/\/sdg21.eu\/en\/#person"}}]}},"aioseo_meta_data":{"post_id":"24909","title":null,"description":"","keywords":"","keyphrases":null,"primary_term":null,"canonical_url":"","og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-20 21:19:31","updated":"2025-06-04 08:43:37","seo_analyzer_scan_date":null},"_links":{"self":[{"href":"https:\/\/sdg21.eu\/en\/wp-json\/wp\/v2\/blog\/24909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sdg21.eu\/en\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/sdg21.eu\/en\/wp-json\/wp\/v2\/types\/blog"}],"author":[{"embeddable":true,"href":"https:\/\/sdg21.eu\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/sdg21.eu\/en\/wp-json\/wp\/v2\/blog\/24909\/revisions"}],"wp:attachment":[{"href":"https:\/\/sdg21.eu\/en\/wp-json\/wp\/v2\/media?parent=24909"}],"wp:term":[{"taxonomy":"blog-kategorie","embeddable":true,"href":"https:\/\/sdg21.eu\/en\/wp-json\/wp\/v2\/blog-kategorie?post=24909"},{"taxonomy":"blog-schlagwort","embeddable":true,"href":"https:\/\/sdg21.eu\/en\/wp-json\/wp\/v2\/blog-schlagwort?post=24909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}