{"id":25045,"date":"2016-04-04T19:41:26","date_gmt":"2016-04-04T17:41:26","guid":{"rendered":"http:\/\/sdg21.eu\/?post_type=blog&#038;p=25045"},"modified":"2020-11-26T19:42:12","modified_gmt":"2020-11-26T18:42:12","slug":"breeam-neue-kriterien-fuer-die-internationale-gebaeudebewertung","status":"publish","type":"blog","link":"https:\/\/sdg21.eu\/en\/blog\/breeam-neue-kriterien-fuer-die-internationale-gebaeudebewertung","title":{"rendered":"BREEAM: new criteria for international building assessment"},"content":{"rendered":"<p>At the end of March 2016, the UK Building Research Establishment Environmental Assessment Method (BREEAM) published new criteria for the international sustainability rating for buildings (BREEAM International New Construction 2016 - NC 2016). These replace the previous rating scheme which had been on the market since 2013. Further information can be found on the website of the Cologne Eco-Institute<\/p>","protected":false},"excerpt":{"rendered":"<p>At the end of March 2016, the UK Building Research Establishment Environmental Assessment Method (BREEAM) published new criteria for the international sustainability rating for buildings (BREEAM International New Construction 2016 - NC 2016). These replace the previous rating scheme which had been on the market since 2013. Further information can be found on the website of the Cologne Eco-Institute<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"template":"","format":"standard","blog-kategorie":[784,828],"blog-schlagwort":[],"class_list":{"0":"post-25045","1":"blog","2":"type-blog","3":"status-publish","4":"format-standard","6":"blog-kategorie-europa-ohne-de","7":"blog-kategorie-zertifzierung-labels","8":"gallery-content-unit","9":"czr-hentry"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ende M\u00e4rz 2016 hat die britische Building Research Establishment Environmental Assessment Method (BREEAM) neue Kriterien f\u00fcr die internationale Nachhaltigkeitsbewertung f\u00fcr Geb\u00e4ude ver\u00f6ffentlicht (BREEAM International New Construction 2016 \u2013 NC 2016). Diese ersetzen das vorherige Bewertungsschema, das seit 2013 auf dem Markt war. Weitere Informationen dazu finden Sie auf der Webseite des K\u00f6lner Eco-Instituts\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"sdg21-Redaktion\"\/>\n\t<meta name=\"google-site-verification\" content=\"google-site-verification=iM5-SDV9qoipUL1b4I0aVhHIOQi1wv0MougIaW1ugnQ\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/sdg21.eu\/en\/blog\/breeam-neue-kriterien-fuer-die-internationale-gebaeudebewertung\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog\\\/breeam-neue-kriterien-fuer-die-internationale-gebaeudebewertung#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog#listItem\",\"name\":\"Blog-Beitr\\u00e4ge\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog#listItem\",\"position\":2,\"name\":\"Blog-Beitr\\u00e4ge\",\"item\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog-kategorie\\\/auszeichnungen#listItem\",\"name\":\"Auszeichnungen\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog-kategorie\\\/auszeichnungen#listItem\",\"position\":3,\"name\":\"Auszeichnungen\",\"item\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog-kategorie\\\/auszeichnungen\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog-kategorie\\\/auszeichnungen\\\/zertifzierung-labels#listItem\",\"name\":\"Zertifzierung &amp; Labels\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog#listItem\",\"name\":\"Blog-Beitr\\u00e4ge\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog-kategorie\\\/auszeichnungen\\\/zertifzierung-labels#listItem\",\"position\":4,\"name\":\"Zertifzierung &amp; Labels\",\"item\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog-kategorie\\\/auszeichnungen\\\/zertifzierung-labels\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog\\\/breeam-neue-kriterien-fuer-die-internationale-gebaeudebewertung#listItem\",\"name\":\"BREEAM: neue Kriterien f\\u00fcr die internationale Geb\\u00e4udebewertung\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog-kategorie\\\/auszeichnungen#listItem\",\"name\":\"Auszeichnungen\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog\\\/breeam-neue-kriterien-fuer-die-internationale-gebaeudebewertung#listItem\",\"position\":5,\"name\":\"BREEAM: neue Kriterien f\\u00fcr die internationale Geb\\u00e4udebewertung\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog-kategorie\\\/auszeichnungen\\\/zertifzierung-labels#listItem\",\"name\":\"Zertifzierung &amp; Labels\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/#person\",\"name\":\"sdg21-Redaktion\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/author\\\/wolpensinger#author\",\"url\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/author\\\/wolpensinger\",\"name\":\"sdg21-Redaktion\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog\\\/breeam-neue-kriterien-fuer-die-internationale-gebaeudebewertung#webpage\",\"url\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog\\\/breeam-neue-kriterien-fuer-die-internationale-gebaeudebewertung\",\"name\":\"BREEAM: neue Kriterien f\\u00fcr die internationale Geb\\u00e4udebewertung | sdg21\",\"description\":\"Ende M\\u00e4rz 2016 hat die britische Building Research Establishment Environmental Assessment Method (BREEAM) neue Kriterien f\\u00fcr die internationale Nachhaltigkeitsbewertung f\\u00fcr Geb\\u00e4ude ver\\u00f6ffentlicht (BREEAM International New Construction 2016 \\u2013 NC 2016). Diese ersetzen das vorherige Bewertungsschema, das seit 2013 auf dem Markt war. Weitere Informationen dazu finden Sie auf der Webseite des K\\u00f6lner Eco-Instituts\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/blog\\\/breeam-neue-kriterien-fuer-die-internationale-gebaeudebewertung#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/author\\\/wolpensinger#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/author\\\/wolpensinger#author\"},\"datePublished\":\"2016-04-04T19:41:26+02:00\",\"dateModified\":\"2020-11-26T19:42:12+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/\",\"name\":\"sdg21\",\"description\":\"Webdatenbank nachhaltiger Siedlungen und Quartiere\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/sdg21.eu\\\/en\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"BREEAM: new criteria for international building assessment | sdg21","description":"At the end of March 2016, the UK Building Research Establishment Environmental Assessment Method (BREEAM) published new criteria for the international sustainability rating for buildings (BREEAM International New Construction 2016 - NC 2016). These replace the previous rating scheme which had been on the market since 2013. Further information can be found on the website of the Cologne Eco-Institute","canonical_url":"https:\/\/sdg21.eu\/en\/blog\/breeam-neue-kriterien-fuer-die-internationale-gebaeudebewertung","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"google-site-verification=iM5-SDV9qoipUL1b4I0aVhHIOQi1wv0MougIaW1ugnQ","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/sdg21.eu\/en\/blog\/breeam-neue-kriterien-fuer-die-internationale-gebaeudebewertung#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/sdg21.eu\/en\/#listItem","position":1,"name":"Home","item":"https:\/\/sdg21.eu\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/sdg21.eu\/en\/blog#listItem","name":"Blog-Beitr\u00e4ge"}},{"@type":"ListItem","@id":"https:\/\/sdg21.eu\/en\/blog#listItem","position":2,"name":"Blog-Beitr\u00e4ge","item":"https:\/\/sdg21.eu\/en\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/sdg21.eu\/en\/blog-kategorie\/auszeichnungen#listItem","name":"Auszeichnungen"},"previousItem":{"@type":"ListItem","@id":"https:\/\/sdg21.eu\/en\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/sdg21.eu\/en\/blog-kategorie\/auszeichnungen#listItem","position":3,"name":"Auszeichnungen","item":"https:\/\/sdg21.eu\/en\/blog-kategorie\/auszeichnungen","nextItem":{"@type":"ListItem","@id":"https:\/\/sdg21.eu\/en\/blog-kategorie\/auszeichnungen\/zertifzierung-labels#listItem","name":"Zertifzierung &amp; Labels"},"previousItem":{"@type":"ListItem","@id":"https:\/\/sdg21.eu\/en\/blog#listItem","name":"Blog-Beitr\u00e4ge"}},{"@type":"ListItem","@id":"https:\/\/sdg21.eu\/en\/blog-kategorie\/auszeichnungen\/zertifzierung-labels#listItem","position":4,"name":"Zertifzierung &amp; Labels","item":"https:\/\/sdg21.eu\/en\/blog-kategorie\/auszeichnungen\/zertifzierung-labels","nextItem":{"@type":"ListItem","@id":"https:\/\/sdg21.eu\/en\/blog\/breeam-neue-kriterien-fuer-die-internationale-gebaeudebewertung#listItem","name":"BREEAM: neue Kriterien f\u00fcr die internationale Geb\u00e4udebewertung"},"previousItem":{"@type":"ListItem","@id":"https:\/\/sdg21.eu\/en\/blog-kategorie\/auszeichnungen#listItem","name":"Auszeichnungen"}},{"@type":"ListItem","@id":"https:\/\/sdg21.eu\/en\/blog\/breeam-neue-kriterien-fuer-die-internationale-gebaeudebewertung#listItem","position":5,"name":"BREEAM: neue Kriterien f\u00fcr die internationale Geb\u00e4udebewertung","previousItem":{"@type":"ListItem","@id":"https:\/\/sdg21.eu\/en\/blog-kategorie\/auszeichnungen\/zertifzierung-labels#listItem","name":"Zertifzierung &amp; Labels"}}]},{"@type":"Person","@id":"https:\/\/sdg21.eu\/en\/#person","name":"sdg21-Redaktion"},{"@type":"Person","@id":"https:\/\/sdg21.eu\/en\/author\/wolpensinger#author","url":"https:\/\/sdg21.eu\/en\/author\/wolpensinger","name":"sdg21-Redaktion"},{"@type":"WebPage","@id":"https:\/\/sdg21.eu\/en\/blog\/breeam-neue-kriterien-fuer-die-internationale-gebaeudebewertung#webpage","url":"https:\/\/sdg21.eu\/en\/blog\/breeam-neue-kriterien-fuer-die-internationale-gebaeudebewertung","name":"BREEAM: neue Kriterien f\u00fcr die internationale Geb\u00e4udebewertung | sdg21","description":"Ende M\u00e4rz 2016 hat die britische Building Research Establishment Environmental Assessment Method (BREEAM) neue Kriterien f\u00fcr die internationale Nachhaltigkeitsbewertung f\u00fcr Geb\u00e4ude ver\u00f6ffentlicht (BREEAM International New Construction 2016 \u2013 NC 2016). Diese ersetzen das vorherige Bewertungsschema, das seit 2013 auf dem Markt war. Weitere Informationen dazu finden Sie auf der Webseite des K\u00f6lner Eco-Instituts","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/sdg21.eu\/en\/#website"},"breadcrumb":{"@id":"https:\/\/sdg21.eu\/en\/blog\/breeam-neue-kriterien-fuer-die-internationale-gebaeudebewertung#breadcrumblist"},"author":{"@id":"https:\/\/sdg21.eu\/en\/author\/wolpensinger#author"},"creator":{"@id":"https:\/\/sdg21.eu\/en\/author\/wolpensinger#author"},"datePublished":"2016-04-04T19:41:26+02:00","dateModified":"2020-11-26T19:42:12+01:00"},{"@type":"WebSite","@id":"https:\/\/sdg21.eu\/en\/#website","url":"https:\/\/sdg21.eu\/en\/","name":"sdg21","description":"Webdatenbank nachhaltiger Siedlungen und Quartiere","inLanguage":"en-GB","publisher":{"@id":"https:\/\/sdg21.eu\/en\/#person"}}]}},"aioseo_meta_data":{"post_id":"25045","title":null,"description":"","keywords":"","keyphrases":null,"primary_term":null,"canonical_url":"","og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-20 21:19:32","updated":"2025-06-04 08:19:58","seo_analyzer_scan_date":null},"_links":{"self":[{"href":"https:\/\/sdg21.eu\/en\/wp-json\/wp\/v2\/blog\/25045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sdg21.eu\/en\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/sdg21.eu\/en\/wp-json\/wp\/v2\/types\/blog"}],"author":[{"embeddable":true,"href":"https:\/\/sdg21.eu\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/sdg21.eu\/en\/wp-json\/wp\/v2\/blog\/25045\/revisions"}],"wp:attachment":[{"href":"https:\/\/sdg21.eu\/en\/wp-json\/wp\/v2\/media?parent=25045"}],"wp:term":[{"taxonomy":"blog-kategorie","embeddable":true,"href":"https:\/\/sdg21.eu\/en\/wp-json\/wp\/v2\/blog-kategorie?post=25045"},{"taxonomy":"blog-schlagwort","embeddable":true,"href":"https:\/\/sdg21.eu\/en\/wp-json\/wp\/v2\/blog-schlagwort?post=25045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}